{"id":3141,"date":"2021-10-27T19:08:46","date_gmt":"2021-10-27T19:08:46","guid":{"rendered":"http:\/\/wp.fidex.com.ua\/hub\/?post_type=portfolio&#038;p=3141"},"modified":"2021-10-27T19:08:46","modified_gmt":"2021-10-27T19:08:46","slug":"dont-be-fooled-by-design","status":"publish","type":"portfolio","link":"https:\/\/wp.fidex.com.ua\/hub\/portfolio\/dont-be-fooled-by-design\/","title":{"rendered":"Don&#8217;t Be Fooled By Design"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3141\" class=\"elementor elementor-3141\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-section elementor-top-section elementor-element elementor-element-d64ca7c elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d64ca7c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b5dfd68\" data-id=\"b5dfd68\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-999f05f elementor-widget elementor-widget-alx-header\" data-id=\"999f05f\" data-element_type=\"widget\" data-widget_type=\"alx-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"header\" id=\"999f05f\">\n            <style>.elementor-1939 .elementor-element.elementor-element-f3a8230{padding:0px 0px 0px 0px;}.elementor-1939 .elementor-element.elementor-element-c23aef7 .alx-slider-control__dots{justify-content:center;}.elementor-1939 .elementor-element.elementor-element-c23aef7 > .elementor-widget-container{padding:0px 0px 0px 0px;}<\/style>\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1939\" class=\"elementor elementor-1939\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f3a8230 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f3a8230\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ff7ec40\" data-id=\"ff7ec40\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c23aef7 elementor-widget elementor-widget-alx-header-builder\" data-id=\"c23aef7\" data-element_type=\"widget\" data-widget_type=\"alx-header-builder.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n                    <nav class=\"alx-header-builds alx-header navbar navbar-Hub navbar-custom nav-bright navbar-fixed-top alx-header-center\" id=\"c23aef7\">\n                <div class=\"container\">\n                 \n                    <div class=\"navbar-header\">\n                        <!-- toggle mobile navigation-->\n                        <a href=\"#\" class=\"alx-toggle-nav\">\n                            <span><\/span>\n                        <\/a>\n\n                        <a class=\"alx-logo navbar-brand\" href=\"https:\/\/wp.fidex.com.ua\/hub\/\">\n                            <img decoding=\"async\" alt=\"Hub - Creative and Business, Multipurpose WordPress Theme\" src=\"https:\/\/wp.fidex.com.ua\/hub\/wp-content\/uploads\/2020\/11\/logodark.png\" class=\"logo\"><img decoding=\"async\" alt=\"Hub - Creative and Business, Multipurpose WordPress Theme\" src=\"https:\/\/wp.fidex.com.ua\/hub\/wp-content\/uploads\/2020\/11\/logodark.png\" class=\"logodark\">                        <\/a>\n                    <\/div>\n                    <!-- Collect the nav links, forms, and other content for toggling-->\n                    <div class=\"alx-header-collapse\">\n\n                        <div class=\"nav navbar-nav alx-header-center__flex-1\"><ul>\n<li id=\"menu-item-45\" class=\"menu-item-45\"><a><\/a><\/li>\n<li id=\"menu-item-72\" class=\"menu-item-72\"><a><\/a><\/li>\n<li id=\"menu-item-81\" class=\"menu-item-81\"><a><\/a><\/li>\n<li id=\"menu-item-248\" class=\"menu-item-248\"><a><\/a><\/li>\n<li id=\"menu-item-3468\" class=\"menu-item-3468\"><a><\/a><\/li>\n<li id=\"menu-item-2761\" class=\"menu-item-2761\"><a><\/a><\/li>\n<li id=\"menu-item-2317\" class=\"menu-item-2317\"><a><\/a><\/li>\n<li id=\"menu-item-2820\" class=\"menu-item-2820\"><a><\/a><\/li>\n<li id=\"menu-item-2111\" class=\"menu-item-2111\"><a><\/a><\/li>\n<li id=\"menu-item-4076\" class=\"menu-item-4076\"><a><\/a><\/li>\n<li id=\"menu-item-2442\" class=\"menu-item-2442\"><a><\/a><\/li>\n<li id=\"menu-item-2832\" class=\"menu-item-2832\"><a><\/a><\/li>\n<li id=\"menu-item-258\" class=\"menu-item-258\"><a><\/a><\/li>\n<li id=\"menu-item-4157\" class=\"menu-item-4157\"><a><\/a><\/li>\n<li id=\"menu-item-2615\" class=\"menu-item-2615\"><a><\/a><\/li>\n<li id=\"menu-item-4577\" class=\"menu-item-4577\"><a><\/a><\/li>\n<li id=\"menu-item-4578\" class=\"menu-item-4578\"><a><\/a><\/li>\n<li id=\"menu-item-207\" class=\"menu-item-207\"><a><\/a><\/li>\n<li id=\"menu-item-3940\" class=\"menu-item-3940\"><a><\/a><\/li>\n<li id=\"menu-item-3792\" class=\"menu-item-3792\"><a><\/a><\/li>\n<li id=\"menu-item-4033\" class=\"menu-item-4033\"><a><\/a><\/li>\n<li id=\"menu-item-4134\" class=\"menu-item-4134\"><a><\/a><\/li>\n<li id=\"menu-item-214\" class=\"menu-item-214\"><a><\/a><\/li>\n<li id=\"menu-item-2544\" class=\"menu-item-2544\"><a><\/a><\/li>\n<li id=\"menu-item-3496\" class=\"menu-item-3496\"><a><\/a><\/li>\n<li id=\"menu-item-3506\" class=\"menu-item-3506\"><a><\/a><\/li>\n<li id=\"menu-item-2680\" class=\"menu-item-2680\"><a><\/a><\/li>\n<li id=\"menu-item-1896\" class=\"menu-item-1896\"><a><\/a><\/li>\n<li id=\"menu-item-2376\" class=\"menu-item-2376\"><a><\/a><\/li>\n<li id=\"menu-item-5761\" class=\"menu-item-5761\"><a><\/a><\/li>\n<li id=\"menu-item-3444\" class=\"menu-item-3444\"><a><\/a><\/li>\n<li id=\"menu-item-3663\" class=\"menu-item-3663\"><a><\/a><\/li>\n<li id=\"menu-item-541\" class=\"menu-item-541\"><a><\/a><\/li>\n<li id=\"menu-item-996\" class=\"menu-item-996\"><a><\/a><\/li>\n<li id=\"menu-item-6111\" class=\"menu-item-6111\"><a><\/a><\/li>\n<li id=\"menu-item-75\" class=\"menu-item-75\"><a><\/a><\/li>\n<li id=\"menu-item-176\" class=\"menu-item-176\"><a><\/a><\/li>\n<li id=\"menu-item-1826\" class=\"menu-item-1826\"><a><\/a><\/li>\n<li id=\"menu-item-3385\" class=\"menu-item-3385\"><a><\/a><\/li>\n<li id=\"menu-item-3412\" class=\"menu-item-3412\"><a><\/a><\/li>\n<li id=\"menu-item-3405\" class=\"menu-item-3405\"><a><\/a><\/li>\n<li id=\"menu-item-4579\" class=\"menu-item-4579\"><a><\/a><\/li>\n<li id=\"menu-item-4415\" class=\"menu-item-4415\"><a><\/a><\/li>\n<li id=\"menu-item-4404\" class=\"menu-item-4404\"><a><\/a><\/li>\n<li id=\"menu-item-4451\" class=\"menu-item-4451\"><a><\/a><\/li>\n<li id=\"menu-item-4348\" class=\"menu-item-4348\"><a><\/a><\/li>\n<li id=\"menu-item-4380\" class=\"menu-item-4380\"><a><\/a><\/li>\n<li id=\"menu-item-4519\" class=\"menu-item-4519\"><a><\/a><\/li>\n<li id=\"menu-item-6677\" class=\"menu-item-6677\"><a><\/a><\/li>\n<li id=\"menu-item-4264\" class=\"menu-item-4264\"><a><\/a><\/li>\n<li id=\"menu-item-4613\" class=\"menu-item-4613\"><a><\/a><\/li>\n<li id=\"menu-item-373\" class=\"menu-item-373\"><a><\/a><\/li>\n<li id=\"menu-item-246\" class=\"menu-item-246\"><a><\/a><\/li>\n<li id=\"menu-item-2193\" class=\"menu-item-2193\"><a><\/a><\/li>\n<li id=\"menu-item-2292\" class=\"menu-item-2292\"><a><\/a><\/li>\n<li id=\"menu-item-3082\" class=\"menu-item-3082\"><a><\/a><\/li>\n<li id=\"menu-item-6950\" class=\"menu-item-6950\"><a><\/a><\/li>\n<li id=\"menu-item-2668\" class=\"menu-item-2668\"><a><\/a><\/li>\n<li id=\"menu-item-3606\" class=\"menu-item-3606\"><a><\/a><\/li>\n<li id=\"menu-item-3542\" class=\"menu-item-3542\"><a><\/a><\/li>\n<li id=\"menu-item-4576\" class=\"menu-item-4576\"><a><\/a><\/li>\n<li id=\"menu-item-3427\" class=\"menu-item-3427\"><a><\/a><\/li>\n<li id=\"menu-item-3433\" class=\"menu-item-3433\"><a><\/a><\/li>\n<li id=\"menu-item-3726\" class=\"menu-item-3726\"><a><\/a><\/li>\n<li id=\"menu-item-2716\" class=\"menu-item-2716\"><a><\/a><\/li>\n<li id=\"menu-item-3566\" class=\"menu-item-3566\"><a><\/a><\/li>\n<li id=\"menu-item-4737\" class=\"menu-item-4737\"><a><\/a><\/li>\n<li id=\"menu-item-5729\" class=\"menu-item-5729\"><a><\/a><\/li>\n<li id=\"menu-item-3213\" class=\"menu-item-3213\"><a><\/a><\/li>\n<li id=\"menu-item-3198\" class=\"menu-item-3198\"><a><\/a><\/li>\n<li id=\"menu-item-3273\" class=\"menu-item-3273\"><a><\/a><\/li>\n<li id=\"menu-item-3292\" class=\"menu-item-3292\"><a><\/a><\/li>\n<li id=\"menu-item-3313\" class=\"menu-item-3313\"><a><\/a><\/li>\n<li id=\"menu-item-3299\" class=\"menu-item-3299\"><a><\/a><\/li>\n<li id=\"menu-item-3318\" class=\"menu-item-3318\"><a><\/a><\/li>\n<li id=\"menu-item-3326\" class=\"menu-item-3326\"><a><\/a><\/li>\n<li id=\"menu-item-3331\" class=\"menu-item-3331\"><a><\/a><\/li>\n<li id=\"menu-item-3340\" class=\"menu-item-3340\"><a><\/a><\/li>\n<li id=\"menu-item-3348\" class=\"menu-item-3348\"><a><\/a><\/li>\n<li id=\"menu-item-3228\" class=\"menu-item-3228\"><a><\/a><\/li>\n<li id=\"menu-item-3237\" class=\"menu-item-3237\"><a><\/a><\/li>\n<li id=\"menu-item-3244\" class=\"menu-item-3244\"><a><\/a><\/li>\n<li id=\"menu-item-3252\" class=\"menu-item-3252\"><a><\/a><\/li>\n<li id=\"menu-item-3259\" class=\"menu-item-3259\"><a><\/a><\/li>\n<li id=\"menu-item-3266\" class=\"menu-item-3266\"><a><\/a><\/li>\n<li id=\"menu-item-3285\" class=\"menu-item-3285\"><a><\/a><\/li>\n<li id=\"menu-item-2808\" class=\"menu-item-2808\"><a><\/a><\/li>\n<li id=\"menu-item-2754\" class=\"menu-item-2754\"><a><\/a><\/li>\n<\/ul><\/div>\n\n\n                        <div class=\"nav navbar-nav pull-right\"><ul>\n<li class=\"menu-item-45\"><a><\/a><\/li>\n<li class=\"menu-item-72\"><a><\/a><\/li>\n<li class=\"menu-item-81\"><a><\/a><\/li>\n<li class=\"menu-item-248\"><a><\/a><\/li>\n<li class=\"menu-item-3468\"><a><\/a><\/li>\n<li class=\"menu-item-2761\"><a><\/a><\/li>\n<li class=\"menu-item-2317\"><a><\/a><\/li>\n<li class=\"menu-item-2820\"><a><\/a><\/li>\n<li class=\"menu-item-2111\"><a><\/a><\/li>\n<li class=\"menu-item-4076\"><a><\/a><\/li>\n<li class=\"menu-item-2442\"><a><\/a><\/li>\n<li class=\"menu-item-2832\"><a><\/a><\/li>\n<li class=\"menu-item-258\"><a><\/a><\/li>\n<li class=\"menu-item-4157\"><a><\/a><\/li>\n<li class=\"menu-item-2615\"><a><\/a><\/li>\n<li class=\"menu-item-4577\"><a><\/a><\/li>\n<li class=\"menu-item-4578\"><a><\/a><\/li>\n<li class=\"menu-item-207\"><a><\/a><\/li>\n<li class=\"menu-item-3940\"><a><\/a><\/li>\n<li class=\"menu-item-3792\"><a><\/a><\/li>\n<li class=\"menu-item-4033\"><a><\/a><\/li>\n<li class=\"menu-item-4134\"><a><\/a><\/li>\n<li class=\"menu-item-214\"><a><\/a><\/li>\n<li class=\"menu-item-2544\"><a><\/a><\/li>\n<li class=\"menu-item-3496\"><a><\/a><\/li>\n<li class=\"menu-item-3506\"><a><\/a><\/li>\n<li class=\"menu-item-2680\"><a><\/a><\/li>\n<li class=\"menu-item-1896\"><a><\/a><\/li>\n<li class=\"menu-item-2376\"><a><\/a><\/li>\n<li class=\"menu-item-5761\"><a><\/a><\/li>\n<li class=\"menu-item-3444\"><a><\/a><\/li>\n<li class=\"menu-item-3663\"><a><\/a><\/li>\n<li class=\"menu-item-541\"><a><\/a><\/li>\n<li class=\"menu-item-996\"><a><\/a><\/li>\n<li class=\"menu-item-6111\"><a><\/a><\/li>\n<li class=\"menu-item-75\"><a><\/a><\/li>\n<li class=\"menu-item-176\"><a><\/a><\/li>\n<li class=\"menu-item-1826\"><a><\/a><\/li>\n<li class=\"menu-item-3385\"><a><\/a><\/li>\n<li class=\"menu-item-3412\"><a><\/a><\/li>\n<li class=\"menu-item-3405\"><a><\/a><\/li>\n<li class=\"menu-item-4579\"><a><\/a><\/li>\n<li class=\"menu-item-4415\"><a><\/a><\/li>\n<li class=\"menu-item-4404\"><a><\/a><\/li>\n<li class=\"menu-item-4451\"><a><\/a><\/li>\n<li class=\"menu-item-4348\"><a><\/a><\/li>\n<li class=\"menu-item-4380\"><a><\/a><\/li>\n<li class=\"menu-item-4519\"><a><\/a><\/li>\n<li class=\"menu-item-6677\"><a><\/a><\/li>\n<li class=\"menu-item-4264\"><a><\/a><\/li>\n<li class=\"menu-item-4613\"><a><\/a><\/li>\n<li class=\"menu-item-373\"><a><\/a><\/li>\n<li class=\"menu-item-246\"><a><\/a><\/li>\n<li class=\"menu-item-2193\"><a><\/a><\/li>\n<li class=\"menu-item-2292\"><a><\/a><\/li>\n<li class=\"menu-item-3082\"><a><\/a><\/li>\n<li class=\"menu-item-6950\"><a><\/a><\/li>\n<li class=\"menu-item-2668\"><a><\/a><\/li>\n<li class=\"menu-item-3606\"><a><\/a><\/li>\n<li class=\"menu-item-3542\"><a><\/a><\/li>\n<li class=\"menu-item-4576\"><a><\/a><\/li>\n<li class=\"menu-item-3427\"><a><\/a><\/li>\n<li class=\"menu-item-3433\"><a><\/a><\/li>\n<li class=\"menu-item-3726\"><a><\/a><\/li>\n<li class=\"menu-item-2716\"><a><\/a><\/li>\n<li class=\"menu-item-3566\"><a><\/a><\/li>\n<li class=\"menu-item-4737\"><a><\/a><\/li>\n<li class=\"menu-item-5729\"><a><\/a><\/li>\n<li class=\"menu-item-3213\"><a><\/a><\/li>\n<li class=\"menu-item-3198\"><a><\/a><\/li>\n<li class=\"menu-item-3273\"><a><\/a><\/li>\n<li class=\"menu-item-3292\"><a><\/a><\/li>\n<li class=\"menu-item-3313\"><a><\/a><\/li>\n<li class=\"menu-item-3299\"><a><\/a><\/li>\n<li class=\"menu-item-3318\"><a><\/a><\/li>\n<li class=\"menu-item-3326\"><a><\/a><\/li>\n<li class=\"menu-item-3331\"><a><\/a><\/li>\n<li class=\"menu-item-3340\"><a><\/a><\/li>\n<li class=\"menu-item-3348\"><a><\/a><\/li>\n<li class=\"menu-item-3228\"><a><\/a><\/li>\n<li class=\"menu-item-3237\"><a><\/a><\/li>\n<li class=\"menu-item-3244\"><a><\/a><\/li>\n<li class=\"menu-item-3252\"><a><\/a><\/li>\n<li class=\"menu-item-3259\"><a><\/a><\/li>\n<li class=\"menu-item-3266\"><a><\/a><\/li>\n<li class=\"menu-item-3285\"><a><\/a><\/li>\n<li class=\"menu-item-2808\"><a><\/a><\/li>\n<li class=\"menu-item-2754\"><a><\/a><\/li>\n<\/ul><\/div>\n\n                        \n         <div class=\"alx-mini-cart \">\n             <a href=\"https:\/\/wp.fidex.com.ua\/hub\/cart\/\">\n\n                <span class=\"alx-mini-cart-top\">\n                    <span class=\"alx-mini-cart-top-total\">\n                        <i class=\"fa fa-shopping-cart fa-lg\"><\/i>\n                        <span class=\"alx-mini-cart-top-total__badge\">\n                           0                        <\/span>\n                     <\/span>\n                <\/span>\n\n            <\/a>\n\n                             <div class=\"alx-mini-cart-content\">\n                    <div class=\"alx-mini-cart-content__title\">\n                        <h5>My cart<\/h5>\n                    <\/div>\n\n                    <div class=\"alx-mini-cart-content-inner\">\n                        <div class=\"widget woocommerce widget_shopping_cart\"> <div class=\"widget_shopping_cart_content\"><\/div><\/div>                    <\/div>\n                 <\/div>\n            \n            <\/div>\n            \n                        <ul id=\"menu-translate-navigation\" class=\"nav navbar-nav alx-gtranslate\"><li class=\"menu-item menu-item-gtranslate menu-item-has-children notranslate\"><a href=\"#\" data-gt-lang=\"en\" class=\"gt-current-wrapper\">English<\/a><ul class=\"dropdown-menu sub-menu\"><li class=\"menu-item menu-item-gtranslate-child\"><a href=\"#\" data-gt-lang=\"ar\">Arabic<\/a><\/li><li class=\"menu-item menu-item-gtranslate-child\"><a href=\"#\" data-gt-lang=\"zh-CN\">Chinese (Simplified)<\/a><\/li><li class=\"menu-item menu-item-gtranslate-child\"><a href=\"#\" data-gt-lang=\"nl\">Dutch<\/a><\/li><li class=\"menu-item menu-item-gtranslate-child\"><a href=\"#\" data-gt-lang=\"en\" class=\"gt-current-lang\">English<\/a><\/li><li class=\"menu-item menu-item-gtranslate-child\"><a href=\"#\" data-gt-lang=\"et\">Estonian<\/a><\/li><li class=\"menu-item menu-item-gtranslate-child\"><a href=\"#\" data-gt-lang=\"fr\">French<\/a><\/li><li class=\"menu-item menu-item-gtranslate-child\"><a href=\"#\" data-gt-lang=\"de\">German<\/a><\/li><li class=\"menu-item menu-item-gtranslate-child\"><a href=\"#\" data-gt-lang=\"pl\">Polish<\/a><\/li><li class=\"menu-item menu-item-gtranslate-child\"><a href=\"#\" data-gt-lang=\"es\">Spanish<\/a><\/li><li class=\"menu-item menu-item-gtranslate-child\"><a href=\"#\" data-gt-lang=\"uk\">Ukrainian<\/a><\/li><\/ul><\/li><\/ul>\n                    <\/div>\n        \n                <\/div>\n            <\/nav>\n        \n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t        <\/div>\n\n\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a204809 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a204809\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3588bee\" data-id=\"3588bee\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-51a357c elementor-pagination-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"51a357c\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;dots&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/wp.fidex.com.ua\/hub\/wp-content\/uploads\/2020\/11\/49.jpg\" alt=\"49\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/wp.fidex.com.ua\/hub\/wp-content\/uploads\/2020\/11\/48.jpg\" alt=\"48\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/wp.fidex.com.ua\/hub\/wp-content\/uploads\/2020\/11\/demo-scaled.jpg\" alt=\"demo\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f76407d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f76407d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2214537\" data-id=\"2214537\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4497ee1 elementor-widget elementor-widget-heading\" data-id=\"4497ee1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Omg! The Best Design Ever!<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf3a7d5 elementor-widget elementor-widget-text-editor\" data-id=\"cf3a7d5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Completely synergize resource taxing relationships via premier niche markets. Professionally cultivate one-to-one customer service with robust ideas. Dynamically innovate resource-leveling customer service.<\/p><p>Efficiently unleash cross-media information without cross-media value. Quickly maximize timely deliverables for real-time schemas. Dramatically maintain clicks-and-mortar solutions without functional solutions.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6d1628f\" data-id=\"6d1628f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12f661e elementor-view-stacked elementor-position-left elementor-vertical-align-middle elementor-widget-mobile__width-auto elementor-shape-circle elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"12f661e\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span class=\"elementor-icon elementor-animation-\" >\n\t\t\t\t<i aria-hidden=\"true\" class=\"ion ion-android-person\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\tClient:\t\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAdvego.me\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8b4a41 elementor-view-stacked elementor-position-left elementor-vertical-align-middle elementor-widget-mobile__width-auto elementor-shape-circle elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"a8b4a41\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span class=\"elementor-icon elementor-animation-\" >\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-calendar-alt\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\tDate:\t\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t2025 April\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3f55c0 elementor-view-stacked elementor-position-left elementor-vertical-align-middle elementor-widget-mobile__width-auto elementor-shape-circle elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"f3f55c0\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span class=\"elementor-icon elementor-animation-\" >\n\t\t\t\t<i aria-hidden=\"true\" class=\"ion ion-ios-pricetag\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span  >\n\t\t\t\t\t\tService:\t\t\t\t\t<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDesign\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bdc45ae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bdc45ae\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a186da4\" data-id=\"a186da4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b3cdeac elementor-widget elementor-widget-heading\" data-id=\"b3cdeac\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Recent Projects<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93d0b51 elementor-widget elementor-widget-visual-portfolio\" data-id=\"93d0b51\" data-element_type=\"widget\" data-widget_type=\"visual-portfolio.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div\n                    >\n                            \n<div class=\"vp-portfolio vp-uid-7c12e3ea vp-id-3010 \"\n    data-vp-layout=\"slider\" data-vp-content-source=\"post-based\" data-vp-items-style=\"fly\" data-vp-items-click-action=\"url\" data-vp-items-gap=\"25\" data-vp-items-gap-vertical=\"\" data-vp-pagination=\"load-more\" data-vp-next-page-url=\"https:\/\/wp.fidex.com.ua\/hub\/wp-json\/wp\/v2\/portfolio\/3141?vp_page=2\" data-vp-slider-effect=\"slide\" data-vp-slider-items-height=\"150px\" data-vp-slider-items-min-height=\"\" data-vp-slider-slides-per-view=\"4\" data-vp-slider-speed=\"0.3\" data-vp-slider-autoplay=\"6\" data-vp-slider-autoplay-hover-pause=\"false\" data-vp-slider-centered-slides=\"true\" data-vp-slider-loop=\"false\" data-vp-slider-free-mode=\"false\" data-vp-slider-free-mode-sticky=\"false\" data-vp-slider-arrows=\"true\" data-vp-slider-bullets=\"false\" data-vp-slider-bullets-dynamic=\"false\" data-vp-slider-mousewheel=\"false\" data-vp-slider-thumbnails=\"false\" >\n    <div class=\"vp-portfolio__preloader-wrap\">\n        <div class=\"vp-portfolio__preloader\">\n            <img decoding=\"async\" loading=\"eager\" src=\"https:\/\/wp.fidex.com.ua\/hub\/wp-content\/plugins\/visual-portfolio\/assets\/images\/logo-dark.svg\" alt=\"Visual Portfolio, Posts &amp; Image Gallery for WordPress\" width=\"20\" height=\"20\" data-skip-lazy>\n        <\/div>\n    <\/div>\n        <div class=\"vp-portfolio__items-wrap\">\n            \n<div class=\"vp-portfolio__items vp-portfolio__items-style-fly\">\n\n        <article        class=\"vp-portfolio__item-wrap post-2978 portfolio type-portfolio status-publish format-standard has-post-thumbnail hentry portfolio_category-branding portfolio_category-motion portfolio_category-photography vp-portfolio__item-uid-a29efd27\" data-vp-filter=\"branding,motion,photography\" style=\"--vp-images__object-position: 50% 50%;\"         >\n            \n<div class=\"vp-portfolio__item-popup\" data-vp-popup-img=\"https:\/\/wp.fidex.com.ua\/hub\/wp-content\/uploads\/2020\/11\/24.jpg\" data-vp-popup-img-srcset=\"\" data-vp-popup-img-size=\"1920x1080\" data-vp-popup-md-img=\"https:\/\/wp.fidex.com.ua\/hub\/wp-content\/uploads\/2020\/11\/24.jpg\" data-vp-popup-md-img-size=\"800x450\" data-vp-popup-sm-img=\"https:\/\/wp.fidex.com.ua\/hub\/wp-content\/uploads\/2020\/11\/24.jpg\" data-vp-popup-sm-img-size=\"500x281\">\n            <h3 class=\"vp-portfolio__item-popup-title\">24<\/h3>\n        <\/div>\n                        <figure class=\"vp-portfolio__item\">\n                \n<div class=\"vp-portfolio__item-img-wrap\">\n    <div class=\"vp-portfolio__item-img\">\n            <a\n        href=\"https:\/\/wp.fidex.com.ua\/hub\/portfolio\/everyone-loves-design\/\"\n            >\n    \n        <img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/wp.fidex.com.ua\/hub\/wp-content\/uploads\/2020\/11\/24.jpg\" class=\"wp-image-572\" alt=\"\" loading=\"lazy\" \/>\n        <\/a>    <\/div>\n<\/div>\n\n<figcaption class=\"vp-portfolio__item-overlay vp-portfolio__item-align-center\">\n    <div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n            <a\n        href=\"https:\/\/wp.fidex.com.ua\/hub\/portfolio\/everyone-loves-design\/\"\n        tabindex=\"-1\" class=\"vp-portfolio__item-meta\"     >\n    \n        \n<div class=\"vp-portfolio__item-meta-categories\">\n            <div class=\"vp-portfolio__item-meta-category\">\n                <span            >\n    Branding<\/span>        <\/div>\n        <\/div>\n\n<h2 class=\"vp-portfolio__item-meta-title\">\n    Everyone Loves Design<\/h2>\n\n        <\/a>    <\/div>\n<\/figcaption>\n            <\/figure>\n                    <\/article>\n        \n        <article        class=\"vp-portfolio__item-wrap post-3028 portfolio type-portfolio status-publish format-standard has-post-thumbnail hentry portfolio_category-corporate vp-portfolio__item-uid-68845588\" data-vp-filter=\"corporate\" style=\"--vp-images__object-position: 50% 50%;\"         >\n            \n<div class=\"vp-portfolio__item-popup\" data-vp-popup-img=\"https:\/\/wp.fidex.com.ua\/hub\/wp-content\/uploads\/2020\/11\/52.jpg\" data-vp-popup-img-srcset=\"\" data-vp-popup-img-size=\"1920x1080\" data-vp-popup-md-img=\"https:\/\/wp.fidex.com.ua\/hub\/wp-content\/uploads\/2020\/11\/52.jpg\" data-vp-popup-md-img-size=\"800x450\" data-vp-popup-sm-img=\"https:\/\/wp.fidex.com.ua\/hub\/wp-content\/uploads\/2020\/11\/52.jpg\" data-vp-popup-sm-img-size=\"500x281\">\n            <h3 class=\"vp-portfolio__item-popup-title\">52<\/h3>\n        <\/div>\n                        <figure class=\"vp-portfolio__item\">\n                \n<div class=\"vp-portfolio__item-img-wrap\">\n    <div class=\"vp-portfolio__item-img\">\n            <a\n        href=\"https:\/\/wp.fidex.com.ua\/hub\/portfolio\/design-secrets\/\"\n            >\n    \n        <img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/wp.fidex.com.ua\/hub\/wp-content\/uploads\/2020\/11\/52.jpg\" class=\"wp-image-600\" alt=\"\" loading=\"lazy\" \/>\n        <\/a>    <\/div>\n<\/div>\n\n<figcaption class=\"vp-portfolio__item-overlay vp-portfolio__item-align-center\">\n    <div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n            <a\n        href=\"https:\/\/wp.fidex.com.ua\/hub\/portfolio\/design-secrets\/\"\n        tabindex=\"-1\" class=\"vp-portfolio__item-meta\"     >\n    \n        \n<div class=\"vp-portfolio__item-meta-categories\">\n            <div class=\"vp-portfolio__item-meta-category\">\n                <span            >\n    Corporate<\/span>        <\/div>\n        <\/div>\n\n<h2 class=\"vp-portfolio__item-meta-title\">\n    Design Secrets<\/h2>\n\n        <\/a>    <\/div>\n<\/figcaption>\n            <\/figure>\n                    <\/article>\n        \n        <article        class=\"vp-portfolio__item-wrap post-3138 portfolio type-portfolio status-publish format-standard has-post-thumbnail hentry portfolio_category-branding portfolio_category-design portfolio_category-photography vp-portfolio__item-uid-705d0efe\" data-vp-filter=\"branding,design,photography\" style=\"--vp-images__object-position: 50% 50%;\"         >\n            \n<div class=\"vp-portfolio__item-popup\" data-vp-popup-img=\"https:\/\/wp.fidex.com.ua\/hub\/wp-content\/uploads\/2020\/11\/10.jpg\" data-vp-popup-img-srcset=\"\" data-vp-popup-img-size=\"1920x1080\" data-vp-popup-md-img=\"https:\/\/wp.fidex.com.ua\/hub\/wp-content\/uploads\/2020\/11\/10.jpg\" data-vp-popup-md-img-size=\"800x450\" data-vp-popup-sm-img=\"https:\/\/wp.fidex.com.ua\/hub\/wp-content\/uploads\/2020\/11\/10.jpg\" data-vp-popup-sm-img-size=\"500x281\">\n            <h3 class=\"vp-portfolio__item-popup-title\">10<\/h3>\n        <\/div>\n                        <figure class=\"vp-portfolio__item\">\n                \n<div class=\"vp-portfolio__item-img-wrap\">\n    <div class=\"vp-portfolio__item-img\">\n            <a\n        href=\"https:\/\/wp.fidex.com.ua\/hub\/portfolio\/beware-the-design-scam\/\"\n            >\n    \n        <img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/wp.fidex.com.ua\/hub\/wp-content\/uploads\/2020\/11\/10.jpg\" class=\"wp-image-557\" alt=\"\" loading=\"lazy\" \/>\n        <\/a>    <\/div>\n<\/div>\n\n<figcaption class=\"vp-portfolio__item-overlay vp-portfolio__item-align-center\">\n    <div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n            <a\n        href=\"https:\/\/wp.fidex.com.ua\/hub\/portfolio\/beware-the-design-scam\/\"\n        tabindex=\"-1\" class=\"vp-portfolio__item-meta\"     >\n    \n        \n<div class=\"vp-portfolio__item-meta-categories\">\n            <div class=\"vp-portfolio__item-meta-category\">\n                <span            >\n    Branding<\/span>        <\/div>\n        <\/div>\n\n<h2 class=\"vp-portfolio__item-meta-title\">\n    Beware The Design Scam<\/h2>\n\n        <\/a>    <\/div>\n<\/figcaption>\n            <\/figure>\n                    <\/article>\n        \n        <article        class=\"vp-portfolio__item-wrap post-3141 portfolio type-portfolio status-publish format-standard has-post-thumbnail hentry portfolio_category-branding portfolio_category-corporate vp-portfolio__item-uid-46c0209d\" data-vp-filter=\"branding,corporate\" style=\"--vp-images__object-position: 50% 50%;\"         >\n            \n<div class=\"vp-portfolio__item-popup\" data-vp-popup-img=\"https:\/\/wp.fidex.com.ua\/hub\/wp-content\/uploads\/2020\/10\/40.jpg\" data-vp-popup-img-srcset=\"\" data-vp-popup-img-size=\"1920x1080\" data-vp-popup-md-img=\"https:\/\/wp.fidex.com.ua\/hub\/wp-content\/uploads\/2020\/10\/40.jpg\" data-vp-popup-md-img-size=\"800x450\" data-vp-popup-sm-img=\"https:\/\/wp.fidex.com.ua\/hub\/wp-content\/uploads\/2020\/10\/40.jpg\" data-vp-popup-sm-img-size=\"500x281\">\n            <h3 class=\"vp-portfolio__item-popup-title\">40<\/h3>\n        <\/div>\n                        <figure class=\"vp-portfolio__item\">\n                \n<div class=\"vp-portfolio__item-img-wrap\">\n    <div class=\"vp-portfolio__item-img\">\n            <a\n        href=\"https:\/\/wp.fidex.com.ua\/hub\/portfolio\/dont-be-fooled-by-design\/\"\n            >\n    \n        <img decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/wp.fidex.com.ua\/hub\/wp-content\/uploads\/2020\/10\/40.jpg\" class=\"wp-image-164\" alt=\"\" loading=\"lazy\" \/>\n        <\/a>    <\/div>\n<\/div>\n\n<figcaption class=\"vp-portfolio__item-overlay vp-portfolio__item-align-center\">\n    <div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n            <a\n        href=\"https:\/\/wp.fidex.com.ua\/hub\/portfolio\/dont-be-fooled-by-design\/\"\n        tabindex=\"-1\" class=\"vp-portfolio__item-meta\"     >\n    \n        \n<div class=\"vp-portfolio__item-meta-categories\">\n            <div class=\"vp-portfolio__item-meta-category\">\n                <span            >\n    Branding<\/span>        <\/div>\n        <\/div>\n\n<h2 class=\"vp-portfolio__item-meta-title\">\n    Don&#8217;t Be Fooled By Design<\/h2>\n\n        <\/a>    <\/div>\n<\/figcaption>\n            <\/figure>\n                    <\/article>\n        \n<\/div>\n\n<div class=\"vp-portfolio__items-arrow vp-portfolio__items-arrow-prev\" tabindex=\"0\" role=\"button\" aria-label=\"Previous Slide\">\n    \n<svg class=\"vp-svg-icon\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n    <path d=\"M12 4L6 10L12 16\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" fill=\"transparent\" \/>\n<\/svg>\n<\/div>\n<div class=\"vp-portfolio__items-arrow vp-portfolio__items-arrow-next\" tabindex=\"0\" role=\"button\" aria-label=\"Next Slide\">\n    \n<svg class=\"vp-svg-icon\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n    <path d=\"M8 4L14 10L8 16\" stroke=\"currentColor\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\" fill=\"transparent\" \/>\n<\/svg>\n<\/div>\n        <\/div>\n        \n<\/div>\n                    <\/div>\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-31be1eb elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"31be1eb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a5bd4c1\" data-id=\"a5bd4c1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-00542d2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"00542d2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-4d1f213 elementor-invisible\" data-id=\"4d1f213\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c96170 elementor-widget elementor-widget-alx-post-navigation\" data-id=\"1c96170\" data-element_type=\"widget\" data-widget_type=\"alx-post-navigation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\n        <nav>\n                            <ul class=\"alx-posts-navigation\">\n                    <!--next-->\n                                            <li class=\"alx-posts-navigation_previous\">\n                            <a href=\"https:\/\/wp.fidex.com.ua\/hub\/portfolio\/design-secrets\/\" title=\"Design Secrets\" class=\"text-muted\" >\n                                <i class=\"fa fa-angle-left\"><\/i><span>PREVIOUS<\/span>                            <\/a>\n                        <\/li>\n                                        <!--All post link    -->\n                    <li class=\"alx-posts-navigation_all\"><a href=\"\/\"><i aria-hidden=\"true\" class=\"far fa-hand-peace\"><\/i><\/a><\/li>                    <!--prev-->\n                                            <li class=\"alx-posts-navigation_next\">\n                            <a href=\"https:\/\/wp.fidex.com.ua\/hub\/portfolio\/beware-the-design-scam\/\" title=\"Beware The Design Scam\" class=\"text-muted\" >\n                                <span>NEXT<\/span><i class=\"fa fa-angle-right\"><\/i>                            <\/a>\n                        <\/li>\n                    <\/ul>\n                            \n        <\/nav>\n\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Toggle navigation Home Landing Landing \u2013 2 Landing Demos Creative Agency Main Demo Video Application Personal \/ Freelancer Personal \/ Freelancer \u2013 2 Agency Portfolio Digital Artist \/ Photographer Auto ShowRoom Construction \/ Renovation Pages About us 1 About us 2 Our partners Portfolio News 2 Columns 2 Columns SideBar 3 Columns 4 Columns Single<span class=\"screen-reader-text\"><a href=\"https:\/\/wp.fidex.com.ua\/hub\/portfolio\/dont-be-fooled-by-design\/\" rel=\"nofollow\">[&#8230;]<\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":164,"menu_order":7,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"inline_featured_image":false,"_vp_format_video_url":"","_vp_image_focal_point":{"x":0.5,"y":0.5}},"portfolio_category":[20,16],"portfolio_tag":[],"_links":{"self":[{"href":"https:\/\/wp.fidex.com.ua\/hub\/wp-json\/wp\/v2\/portfolio\/3141"}],"collection":[{"href":"https:\/\/wp.fidex.com.ua\/hub\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/wp.fidex.com.ua\/hub\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/wp.fidex.com.ua\/hub\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.fidex.com.ua\/hub\/wp-json\/wp\/v2\/comments?post=3141"}],"version-history":[{"count":0,"href":"https:\/\/wp.fidex.com.ua\/hub\/wp-json\/wp\/v2\/portfolio\/3141\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wp.fidex.com.ua\/hub\/wp-json\/wp\/v2\/media\/164"}],"wp:attachment":[{"href":"https:\/\/wp.fidex.com.ua\/hub\/wp-json\/wp\/v2\/media?parent=3141"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/wp.fidex.com.ua\/hub\/wp-json\/wp\/v2\/portfolio_category?post=3141"},{"taxonomy":"portfolio_tag","embeddable":true,"href":"https:\/\/wp.fidex.com.ua\/hub\/wp-json\/wp\/v2\/portfolio_tag?post=3141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}